{"id":834,"date":"2020-04-14T16:01:36","date_gmt":"2020-04-14T23:01:36","guid":{"rendered":"http:\/\/classesbranchees.csf.bc.ca\/ecoledupacifique\/?page_id=834"},"modified":"2020-04-14T16:01:36","modified_gmt":"2020-04-14T23:01:36","slug":"musique","status":"publish","type":"page","link":"https:\/\/classesbranchees.csf.bc.ca\/ecoledupacifique\/les-nouvelles-de-la-maternelle-premiere\/musique\/","title":{"rendered":"Musique"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":184,"featured_media":0,"parent":97,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/classesbranchees.csf.bc.ca\/ecoledupacifique\/wp-json\/wp\/v2\/pages\/834"}],"collection":[{"href":"https:\/\/classesbranchees.csf.bc.ca\/ecoledupacifique\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/classesbranchees.csf.bc.ca\/ecoledupacifique\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/classesbranchees.csf.bc.ca\/ecoledupacifique\/wp-json\/wp\/v2\/users\/184"}],"replies":[{"embeddable":true,"href":"https:\/\/classesbranchees.csf.bc.ca\/ecoledupacifique\/wp-json\/wp\/v2\/comments?post=834"}],"version-history":[{"count":1,"href":"https:\/\/classesbranchees.csf.bc.ca\/ecoledupacifique\/wp-json\/wp\/v2\/pages\/834\/revisions"}],"predecessor-version":[{"id":835,"href":"https:\/\/classesbranchees.csf.bc.ca\/ecoledupacifique\/wp-json\/wp\/v2\/pages\/834\/revisions\/835"}],"up":[{"embeddable":true,"href":"https:\/\/classesbranchees.csf.bc.ca\/ecoledupacifique\/wp-json\/wp\/v2\/pages\/97"}],"wp:attachment":[{"href":"https:\/\/classesbranchees.csf.bc.ca\/ecoledupacifique\/wp-json\/wp\/v2\/media?parent=834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}